{"id":14823,"date":"2015-02-13T02:17:21","date_gmt":"2015-02-13T02:17:21","guid":{"rendered":"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/"},"modified":"2015-02-13T02:17:21","modified_gmt":"2015-02-13T02:17:21","slug":"el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto","status":"publish","type":"post","link":"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/","title":{"rendered":"El Qarto, la nueva propuesta de rock alternativo en Pasto"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-14822\" src=\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/02\/c421fc71b0223dee41016aae8a0ae2bf.jpg\" alt=\"\" width=\"852\" height=\"357\" srcset=\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/02\/c421fc71b0223dee41016aae8a0ae2bf.jpg 852w, https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/02\/c421fc71b0223dee41016aae8a0ae2bf-300x126.jpg 300w, https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/02\/c421fc71b0223dee41016aae8a0ae2bf-768x322.jpg 768w\" sizes=\"(max-width: 852px) 100vw, 852px\" \/><\/p>\n<p style=\"text-align: justify;\">P\u00e1gina 10 promueve la cultura en todas sus expresiones, es por esto que es un gusto poder apoyar los nuevos emprendimientos musicales en la ciudad y presentar a todos nuestros lectores la banda de rock alternativo <span style=\"line-height: 19.7999992370605px; text-align: justify;\">El Qarto&#8221;.<\/span><\/p>\n<p style=\"text-align: justify;\">En el a\u00f1o 2009 se conforma en la ciudad de Pasto &#8220;Nindo&#8221;, como inicialmente fue bautizado,&nbsp;como parte de un hobbie, un sue\u00f1o de todos sus integrantes que luego se convertir\u00eda en un emprendimiento musical que reun\u00eda toda la pasi\u00f3n que sentian por la m\u00fasica y el deseo por realizar este proyecto.<\/p>\n<p style=\"text-align: justify;\">Durante 5 a\u00f1os buscaron un estilo libre de hacer m\u00fasica, un estilo libre de expresion, de atravesar la vida con notas y letras. Con &#8220;Nindo&#8221; lograron componer y grabar uno que otro demo y realizar varias presentaciones. A finales de 2014 decidieron darle un giro a este proyecto, refrescaron su musica y se reinventaron, ahora se presentan como El Qarto.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Integrantes<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Victor Hugo calvachi (25 a\u00f1os) &#8211; Baterista<\/strong><br \/>Estudiante de Arquitectura Universidad de Nari\u00f1o.<\/p>\n<p style=\"text-align: justify;\"><strong>Juan Esteban gomez (24 a\u00f1os) &#8211;&nbsp;Guitarra<\/strong><br \/>Estudiante de ingenieria de sistemas en Universidad Mariana.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Jeasson belalcazar (25 a\u00f1os) &#8211;&nbsp;vocalista y letra<\/strong><\/p>\n<p style=\"text-align: justify;\">Estudio Medicina en Universidad San Martin.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Dario Estrada (25 a\u00f1os) &#8211;&nbsp;<span style=\"line-height: 19.7999992370605px; text-align: justify;\">Bajo<\/span><\/strong><br \/>Estudiante de M\u00fasica.<\/p>\n<p style=\"text-align: justify;\">A continuaci\u00f3n presentamos su primer videoclip: No Pretendo, un proyecto Nari\u00f1ense grabado en Pasto y el aeropuerto Antonio Nari\u00f1o.<\/p>\n<p style=\"text-align: justify;\">&nbsp;&nbsp;<iframe width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/LxIaxKDJM7k?rel=0\" frameborder=\"0\" allowfullscreen=\"true\" style=\"line-height: 1.8; text-align: left;\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>P\u00e1gina 10 promueve la cultura en todas sus expresiones, es por esto que es un gusto poder apoyar los nuevos emprendimientos musicales en la ciudad y presentar a todos nuestros lectores la banda de rock alternativo El Qarto&#8221;. En el a\u00f1o 2009 se conforma en la ciudad de Pasto &#8220;Nindo&#8221;, como inicialmente fue bautizado,&nbsp;como parte [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":14822,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Qarto, la nueva propuesta de rock alternativo en Pasto | P\u00e1gina10<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Qarto, la nueva propuesta de rock alternativo en Pasto | P\u00e1gina10\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina 10 promueve la cultura en todas sus expresiones, es por esto que es un gusto poder apoyar los nuevos emprendimientos musicales en la ciudad y presentar a todos nuestros lectores la banda de rock alternativo El Qarto&#8221;. En el a\u00f1o 2009 se conforma en la ciudad de Pasto &#8220;Nindo&#8221;, como inicialmente fue bautizado,&nbsp;como parte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/\" \/>\n<meta property=\"og:site_name\" content=\"P\u00e1gina10\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pag10com\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-13T02:17:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/02\/c421fc71b0223dee41016aae8a0ae2bf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"852\" \/>\n\t<meta property=\"og:image:height\" content=\"357\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"P\u00e1gina 10\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Pag10com\" \/>\n<meta name=\"twitter:site\" content=\"@Pag10com\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"P\u00e1gina 10\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/\"},\"author\":{\"name\":\"P\u00e1gina 10\",\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/person\/a7a5d38f0629dfc107f619fbae4f6cc3\"},\"headline\":\"El Qarto, la nueva propuesta de rock alternativo en Pasto\",\"datePublished\":\"2015-02-13T02:17:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/\"},\"wordCount\":250,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/pagina10.com\/web\/#organization\"},\"image\":{\"@id\":\"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/02\/c421fc71b0223dee41016aae8a0ae2bf.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/\",\"url\":\"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/\",\"name\":\"El Qarto, la nueva propuesta de rock alternativo en Pasto | P\u00e1gina10\",\"isPartOf\":{\"@id\":\"https:\/\/pagina10.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/02\/c421fc71b0223dee41016aae8a0ae2bf.jpg\",\"datePublished\":\"2015-02-13T02:17:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/#primaryimage\",\"url\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/02\/c421fc71b0223dee41016aae8a0ae2bf.jpg\",\"contentUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/02\/c421fc71b0223dee41016aae8a0ae2bf.jpg\",\"width\":852,\"height\":357},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/pagina10.com\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Qarto, la nueva propuesta de rock alternativo en Pasto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pagina10.com\/web\/#website\",\"url\":\"https:\/\/pagina10.com\/web\/\",\"name\":\"P\u00e1gina10\",\"description\":\"Peri\u00f3dico Regional\",\"publisher\":{\"@id\":\"https:\/\/pagina10.com\/web\/#organization\"},\"alternateName\":\"P\u00e1gina10 Peri\u00f3dico Regional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pagina10.com\/web\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pagina10.com\/web\/#organization\",\"name\":\"P\u00e1gina10\",\"alternateName\":\"P\u00e1gina10 Peri\u00f3dico Regional\",\"url\":\"https:\/\/pagina10.com\/web\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg\",\"contentUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg\",\"width\":1280,\"height\":720,\"caption\":\"P\u00e1gina10\"},\"image\":{\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pag10com\",\"https:\/\/x.com\/Pag10com\",\"https:\/\/www.instagram.com\/pagina10col\/\",\"https:\/\/youtube.com\/channel\/pag10\",\"https:\/\/www.tiktok.com\/@p10col\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/person\/a7a5d38f0629dfc107f619fbae4f6cc3\",\"name\":\"P\u00e1gina 10\",\"description\":\"P\u00e1gina10.com es un peri\u00f3dico digital que nace en Colombia, en el departamento de Nari\u00f1o, con un enfoque global, fundamentado en cuatro pilares esenciales: la libertad, el pluralismo, la inclusi\u00f3n y la independencia. P\u00e1gina10.com hace referencia a Nari\u00f1o como el d\u00e9cimo departamento creado en Colombia, despu\u00e9s de un proceso pol\u00edtico liderado por actores y actrices regionales con el fin de obtener la independencia y autonom\u00eda de nuestros territorios. Con la creaci\u00f3n de P\u00e1gina10.com se pretende abrir un escenario para el dialogo, la reflexi\u00f3n y el debate que se extienda a otras geograf\u00edas de Am\u00e9rica Latina y del planeta, en una apuesta por transformar colectivamente los desaf\u00edos de un mundo contempor\u00e1neo, m\u00e1s all\u00e1 de las fronteras impuestas.\",\"url\":\"https:\/\/pagina10.com\/web\/author\/mcepeda\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Qarto, la nueva propuesta de rock alternativo en Pasto | P\u00e1gina10","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/","og_locale":"es_ES","og_type":"article","og_title":"El Qarto, la nueva propuesta de rock alternativo en Pasto | P\u00e1gina10","og_description":"P\u00e1gina 10 promueve la cultura en todas sus expresiones, es por esto que es un gusto poder apoyar los nuevos emprendimientos musicales en la ciudad y presentar a todos nuestros lectores la banda de rock alternativo El Qarto&#8221;. En el a\u00f1o 2009 se conforma en la ciudad de Pasto &#8220;Nindo&#8221;, como inicialmente fue bautizado,&nbsp;como parte [&hellip;]","og_url":"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/","og_site_name":"P\u00e1gina10","article_publisher":"https:\/\/www.facebook.com\/pag10com","article_published_time":"2015-02-13T02:17:21+00:00","og_image":[{"width":852,"height":357,"url":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/02\/c421fc71b0223dee41016aae8a0ae2bf.jpg","type":"image\/jpeg"}],"author":"P\u00e1gina 10","twitter_card":"summary_large_image","twitter_creator":"@Pag10com","twitter_site":"@Pag10com","twitter_misc":{"Escrito por":"P\u00e1gina 10","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/#article","isPartOf":{"@id":"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/"},"author":{"name":"P\u00e1gina 10","@id":"https:\/\/pagina10.com\/web\/#\/schema\/person\/a7a5d38f0629dfc107f619fbae4f6cc3"},"headline":"El Qarto, la nueva propuesta de rock alternativo en Pasto","datePublished":"2015-02-13T02:17:21+00:00","mainEntityOfPage":{"@id":"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/"},"wordCount":250,"commentCount":0,"publisher":{"@id":"https:\/\/pagina10.com\/web\/#organization"},"image":{"@id":"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/#primaryimage"},"thumbnailUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/02\/c421fc71b0223dee41016aae8a0ae2bf.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/","url":"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/","name":"El Qarto, la nueva propuesta de rock alternativo en Pasto | P\u00e1gina10","isPartOf":{"@id":"https:\/\/pagina10.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/#primaryimage"},"image":{"@id":"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/#primaryimage"},"thumbnailUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/02\/c421fc71b0223dee41016aae8a0ae2bf.jpg","datePublished":"2015-02-13T02:17:21+00:00","breadcrumb":{"@id":"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/#primaryimage","url":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/02\/c421fc71b0223dee41016aae8a0ae2bf.jpg","contentUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/02\/c421fc71b0223dee41016aae8a0ae2bf.jpg","width":852,"height":357},{"@type":"BreadcrumbList","@id":"https:\/\/pagina10.com\/web\/el-qarto-la-nueva-propuesta-de-rock-alternativo-en-pasto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pagina10.com\/web\/"},{"@type":"ListItem","position":2,"name":"El Qarto, la nueva propuesta de rock alternativo en Pasto"}]},{"@type":"WebSite","@id":"https:\/\/pagina10.com\/web\/#website","url":"https:\/\/pagina10.com\/web\/","name":"P\u00e1gina10","description":"Peri\u00f3dico Regional","publisher":{"@id":"https:\/\/pagina10.com\/web\/#organization"},"alternateName":"P\u00e1gina10 Peri\u00f3dico Regional","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pagina10.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pagina10.com\/web\/#organization","name":"P\u00e1gina10","alternateName":"P\u00e1gina10 Peri\u00f3dico Regional","url":"https:\/\/pagina10.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/","url":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg","contentUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg","width":1280,"height":720,"caption":"P\u00e1gina10"},"image":{"@id":"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pag10com","https:\/\/x.com\/Pag10com","https:\/\/www.instagram.com\/pagina10col\/","https:\/\/youtube.com\/channel\/pag10","https:\/\/www.tiktok.com\/@p10col"]},{"@type":"Person","@id":"https:\/\/pagina10.com\/web\/#\/schema\/person\/a7a5d38f0629dfc107f619fbae4f6cc3","name":"P\u00e1gina 10","description":"P\u00e1gina10.com es un peri\u00f3dico digital que nace en Colombia, en el departamento de Nari\u00f1o, con un enfoque global, fundamentado en cuatro pilares esenciales: la libertad, el pluralismo, la inclusi\u00f3n y la independencia. P\u00e1gina10.com hace referencia a Nari\u00f1o como el d\u00e9cimo departamento creado en Colombia, despu\u00e9s de un proceso pol\u00edtico liderado por actores y actrices regionales con el fin de obtener la independencia y autonom\u00eda de nuestros territorios. Con la creaci\u00f3n de P\u00e1gina10.com se pretende abrir un escenario para el dialogo, la reflexi\u00f3n y el debate que se extienda a otras geograf\u00edas de Am\u00e9rica Latina y del planeta, en una apuesta por transformar colectivamente los desaf\u00edos de un mundo contempor\u00e1neo, m\u00e1s all\u00e1 de las fronteras impuestas.","url":"https:\/\/pagina10.com\/web\/author\/mcepeda\/"}]}},"_links":{"self":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts\/14823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/comments?post=14823"}],"version-history":[{"count":0,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts\/14823\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/media\/14822"}],"wp:attachment":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/media?parent=14823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/categories?post=14823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/tags?post=14823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}