{"id":16390,"date":"2015-06-10T15:05:55","date_gmt":"2015-06-10T15:05:55","guid":{"rendered":"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/"},"modified":"2015-06-10T15:05:55","modified_gmt":"2015-06-10T15:05:55","slug":"listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino","status":"publish","type":"post","link":"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/","title":{"rendered":"Listas las fechas para reposici\u00f3n de clases en colegios de Nari\u00f1o"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-16389\" src=\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/06\/cbc2b925338d4c658606314ef86b5485.jpg\" alt=\"\" width=\"640\" height=\"428\" srcset=\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/06\/cbc2b925338d4c658606314ef86b5485.jpg 640w, https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/06\/cbc2b925338d4c658606314ef86b5485-300x201.jpg 300w, https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/06\/cbc2b925338d4c658606314ef86b5485-450x300.jpg 450w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">De acuerdo a reuni\u00f3n conjunta que se realiz\u00f3 entre el Secretario de Educaci\u00f3n Departamental, \u00c1ngel Garc\u00eda Paredes, y las Directivas del Sindicato del Magisterio de Nari\u00f1o SIMANA \u2013 y de las Asociaciones de Rectores ARIEN y ARCODEN y con el prop\u00f3sito de clarificar y unificar criterios respecto de la reposici\u00f3n del tiempo escolar, se acord\u00f3 que se&nbsp;trabajar\u00e1 acad\u00e9micamente la semana de receso escolar comprendida entre el 5 y el 9 de octubre del a\u00f1o en curso y no se utilizar\u00e1 para la reposici\u00f3n del tiempo, la semana de evaluaci\u00f3n institucional en el mes de diciembre.<\/p>\n<p style=\"text-align: justify;\">Haciendo uso de la autonom\u00eda institucional y con la participaci\u00f3n de los Consejos Directivos Institucionales y con la refrendaci\u00f3n de los Personeros Municipales, se determinar\u00e1n los d\u00edas restantes para la reposici\u00f3n del tiempo escolar.&nbsp;<\/p>\n<p style=\"text-align: justify;\">Los Rectores deben entregar en la Oficina de Atenci\u00f3n al Ciudadano de la Secretar\u00eda de Educaci\u00f3n Departamental, las actas de acuerdo del cronograma de reposici\u00f3n del tiempo escolar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acuerdo a reuni\u00f3n conjunta que se realiz\u00f3 entre el Secretario de Educaci\u00f3n Departamental, \u00c1ngel Garc\u00eda Paredes, y las Directivas del Sindicato del Magisterio de Nari\u00f1o SIMANA \u2013 y de las Asociaciones de Rectores ARIEN y ARCODEN y con el prop\u00f3sito de clarificar y unificar criterios respecto de la reposici\u00f3n del tiempo escolar, se acord\u00f3 [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":16389,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Listas las fechas para reposici\u00f3n de clases en colegios de Nari\u00f1o | P\u00e1gina10<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Listas las fechas para reposici\u00f3n de clases en colegios de Nari\u00f1o | P\u00e1gina10\" \/>\n<meta property=\"og:description\" content=\"De acuerdo a reuni\u00f3n conjunta que se realiz\u00f3 entre el Secretario de Educaci\u00f3n Departamental, \u00c1ngel Garc\u00eda Paredes, y las Directivas del Sindicato del Magisterio de Nari\u00f1o SIMANA \u2013 y de las Asociaciones de Rectores ARIEN y ARCODEN y con el prop\u00f3sito de clarificar y unificar criterios respecto de la reposici\u00f3n del tiempo escolar, se acord\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/\" \/>\n<meta property=\"og:site_name\" content=\"P\u00e1gina10\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pag10com\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-10T15:05:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/06\/cbc2b925338d4c658606314ef86b5485.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"428\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"P\u00e1gina 10\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Pag10com\" \/>\n<meta name=\"twitter:site\" content=\"@Pag10com\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"P\u00e1gina 10\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/\"},\"author\":{\"name\":\"P\u00e1gina 10\",\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/person\/a7a5d38f0629dfc107f619fbae4f6cc3\"},\"headline\":\"Listas las fechas para reposici\u00f3n de clases en colegios de Nari\u00f1o\",\"datePublished\":\"2015-06-10T15:05:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/\"},\"wordCount\":190,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/pagina10.com\/web\/#organization\"},\"image\":{\"@id\":\"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/06\/cbc2b925338d4c658606314ef86b5485.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/\",\"url\":\"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/\",\"name\":\"Listas las fechas para reposici\u00f3n de clases en colegios de Nari\u00f1o | P\u00e1gina10\",\"isPartOf\":{\"@id\":\"https:\/\/pagina10.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/06\/cbc2b925338d4c658606314ef86b5485.jpg\",\"datePublished\":\"2015-06-10T15:05:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/#primaryimage\",\"url\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/06\/cbc2b925338d4c658606314ef86b5485.jpg\",\"contentUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/06\/cbc2b925338d4c658606314ef86b5485.jpg\",\"width\":640,\"height\":428},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/pagina10.com\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listas las fechas para reposici\u00f3n de clases en colegios de Nari\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pagina10.com\/web\/#website\",\"url\":\"https:\/\/pagina10.com\/web\/\",\"name\":\"P\u00e1gina10\",\"description\":\"Peri\u00f3dico Regional\",\"publisher\":{\"@id\":\"https:\/\/pagina10.com\/web\/#organization\"},\"alternateName\":\"P\u00e1gina10 Peri\u00f3dico Regional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pagina10.com\/web\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pagina10.com\/web\/#organization\",\"name\":\"P\u00e1gina10\",\"alternateName\":\"P\u00e1gina10 Peri\u00f3dico Regional\",\"url\":\"https:\/\/pagina10.com\/web\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg\",\"contentUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg\",\"width\":1280,\"height\":720,\"caption\":\"P\u00e1gina10\"},\"image\":{\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pag10com\",\"https:\/\/x.com\/Pag10com\",\"https:\/\/www.instagram.com\/pagina10col\/\",\"https:\/\/youtube.com\/channel\/pag10\",\"https:\/\/www.tiktok.com\/@p10col\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/person\/a7a5d38f0629dfc107f619fbae4f6cc3\",\"name\":\"P\u00e1gina 10\",\"description\":\"P\u00e1gina10.com es un peri\u00f3dico digital que nace en Colombia, en el departamento de Nari\u00f1o, con un enfoque global, fundamentado en cuatro pilares esenciales: la libertad, el pluralismo, la inclusi\u00f3n y la independencia. P\u00e1gina10.com hace referencia a Nari\u00f1o como el d\u00e9cimo departamento creado en Colombia, despu\u00e9s de un proceso pol\u00edtico liderado por actores y actrices regionales con el fin de obtener la independencia y autonom\u00eda de nuestros territorios. Con la creaci\u00f3n de P\u00e1gina10.com se pretende abrir un escenario para el dialogo, la reflexi\u00f3n y el debate que se extienda a otras geograf\u00edas de Am\u00e9rica Latina y del planeta, en una apuesta por transformar colectivamente los desaf\u00edos de un mundo contempor\u00e1neo, m\u00e1s all\u00e1 de las fronteras impuestas.\",\"url\":\"https:\/\/pagina10.com\/web\/author\/mcepeda\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Listas las fechas para reposici\u00f3n de clases en colegios de Nari\u00f1o | P\u00e1gina10","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/","og_locale":"es_ES","og_type":"article","og_title":"Listas las fechas para reposici\u00f3n de clases en colegios de Nari\u00f1o | P\u00e1gina10","og_description":"De acuerdo a reuni\u00f3n conjunta que se realiz\u00f3 entre el Secretario de Educaci\u00f3n Departamental, \u00c1ngel Garc\u00eda Paredes, y las Directivas del Sindicato del Magisterio de Nari\u00f1o SIMANA \u2013 y de las Asociaciones de Rectores ARIEN y ARCODEN y con el prop\u00f3sito de clarificar y unificar criterios respecto de la reposici\u00f3n del tiempo escolar, se acord\u00f3 [&hellip;]","og_url":"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/","og_site_name":"P\u00e1gina10","article_publisher":"https:\/\/www.facebook.com\/pag10com","article_published_time":"2015-06-10T15:05:55+00:00","og_image":[{"width":640,"height":428,"url":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/06\/cbc2b925338d4c658606314ef86b5485.jpg","type":"image\/jpeg"}],"author":"P\u00e1gina 10","twitter_card":"summary_large_image","twitter_creator":"@Pag10com","twitter_site":"@Pag10com","twitter_misc":{"Escrito por":"P\u00e1gina 10","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/#article","isPartOf":{"@id":"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/"},"author":{"name":"P\u00e1gina 10","@id":"https:\/\/pagina10.com\/web\/#\/schema\/person\/a7a5d38f0629dfc107f619fbae4f6cc3"},"headline":"Listas las fechas para reposici\u00f3n de clases en colegios de Nari\u00f1o","datePublished":"2015-06-10T15:05:55+00:00","mainEntityOfPage":{"@id":"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/"},"wordCount":190,"commentCount":0,"publisher":{"@id":"https:\/\/pagina10.com\/web\/#organization"},"image":{"@id":"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/#primaryimage"},"thumbnailUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/06\/cbc2b925338d4c658606314ef86b5485.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/","url":"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/","name":"Listas las fechas para reposici\u00f3n de clases en colegios de Nari\u00f1o | P\u00e1gina10","isPartOf":{"@id":"https:\/\/pagina10.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/#primaryimage"},"image":{"@id":"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/#primaryimage"},"thumbnailUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/06\/cbc2b925338d4c658606314ef86b5485.jpg","datePublished":"2015-06-10T15:05:55+00:00","breadcrumb":{"@id":"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/#primaryimage","url":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/06\/cbc2b925338d4c658606314ef86b5485.jpg","contentUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2015\/06\/cbc2b925338d4c658606314ef86b5485.jpg","width":640,"height":428},{"@type":"BreadcrumbList","@id":"https:\/\/pagina10.com\/web\/listas-las-fechas-para-reposicion-de-clases-en-colegios-de-narino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pagina10.com\/web\/"},{"@type":"ListItem","position":2,"name":"Listas las fechas para reposici\u00f3n de clases en colegios de Nari\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/pagina10.com\/web\/#website","url":"https:\/\/pagina10.com\/web\/","name":"P\u00e1gina10","description":"Peri\u00f3dico Regional","publisher":{"@id":"https:\/\/pagina10.com\/web\/#organization"},"alternateName":"P\u00e1gina10 Peri\u00f3dico Regional","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pagina10.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pagina10.com\/web\/#organization","name":"P\u00e1gina10","alternateName":"P\u00e1gina10 Peri\u00f3dico Regional","url":"https:\/\/pagina10.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/","url":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg","contentUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg","width":1280,"height":720,"caption":"P\u00e1gina10"},"image":{"@id":"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pag10com","https:\/\/x.com\/Pag10com","https:\/\/www.instagram.com\/pagina10col\/","https:\/\/youtube.com\/channel\/pag10","https:\/\/www.tiktok.com\/@p10col"]},{"@type":"Person","@id":"https:\/\/pagina10.com\/web\/#\/schema\/person\/a7a5d38f0629dfc107f619fbae4f6cc3","name":"P\u00e1gina 10","description":"P\u00e1gina10.com es un peri\u00f3dico digital que nace en Colombia, en el departamento de Nari\u00f1o, con un enfoque global, fundamentado en cuatro pilares esenciales: la libertad, el pluralismo, la inclusi\u00f3n y la independencia. P\u00e1gina10.com hace referencia a Nari\u00f1o como el d\u00e9cimo departamento creado en Colombia, despu\u00e9s de un proceso pol\u00edtico liderado por actores y actrices regionales con el fin de obtener la independencia y autonom\u00eda de nuestros territorios. Con la creaci\u00f3n de P\u00e1gina10.com se pretende abrir un escenario para el dialogo, la reflexi\u00f3n y el debate que se extienda a otras geograf\u00edas de Am\u00e9rica Latina y del planeta, en una apuesta por transformar colectivamente los desaf\u00edos de un mundo contempor\u00e1neo, m\u00e1s all\u00e1 de las fronteras impuestas.","url":"https:\/\/pagina10.com\/web\/author\/mcepeda\/"}]}},"_links":{"self":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts\/16390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/comments?post=16390"}],"version-history":[{"count":0,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts\/16390\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/media\/16389"}],"wp:attachment":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/media?parent=16390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/categories?post=16390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/tags?post=16390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}