{"id":51035,"date":"2021-03-08T09:30:42","date_gmt":"2021-03-08T14:30:42","guid":{"rendered":"https:\/\/pagina10.com\/web\/?p=51035"},"modified":"2021-03-08T09:30:42","modified_gmt":"2021-03-08T14:30:42","slug":"narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz","status":"publish","type":"post","link":"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/","title":{"rendered":"Nari\u00f1o conmemora y resalta la lucha de las mujeres por un futuro incluyente y en paz."},"content":{"rendered":"<p style=\"text-align: justify;\">Las mujeres de Nari\u00f1o son aquellas que d\u00eda a d\u00eda se levantan a conquistar sus sue\u00f1os y liderar espacios de toma de decisiones que potencian el desarrollo de un territorio competitivo, sostenible, conectado, seguro, incluyente y en paz.<\/p>\n<p>Desde la Gobernaci\u00f3n de Nari\u00f1o conmemoramos esta fecha que permite recordarle a la sociedad, la lucha por la igualdad, la reivindicaci\u00f3n de los derechos y una vida libre de violencias para las ni\u00f1as y mujeres de Nari\u00f1o.<\/p>\n<p>\u201cDesde la Administraci\u00f3n Departamental y la Secretar\u00eda de Equidad de G\u00e9nero e Inclusi\u00f3n Social \u2013 SEGIS, queremos recordarles a las mujeres que nuestro compromiso es con ustedes y que gracias a la transversalidad que generan nuestros 7 subprogramas, articularemos y desarrollaremos acciones que garanticen su participaci\u00f3n, incidencia en los territorios y una vida libre de violencias\u201d, manifest\u00f3 Secretaria de Equidad de G\u00e9nero e Inclusi\u00f3n Social de la Gobernaci\u00f3n de Nari\u00f1o, Yised Ver\u00f3nica Caicedo.<\/p>\n<p>De esta manera en articulaci\u00f3n con el Comit\u00e9 Departamental de Violencias Basadas en G\u00e9nero, con el apoyo de ONU Mujeres, se llevar\u00e1 a cabo actividades simb\u00f3licas, educativas y culturales que resaltan la labor y el papel fundamental que lideran las mujeres en el crecimiento del territorio.<\/p>\n<p style=\"text-align: center;\"><strong>Agenda conmemoraci\u00f3n D\u00eda Internacional de la Mujer<\/strong><br \/>\n<strong>del 8 al 25 de marzo.<\/strong><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-51036\" src=\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/Captura-de-pantalla-85.png\" alt=\"\" width=\"592\" height=\"455\" srcset=\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/Captura-de-pantalla-85.png 592w, https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/Captura-de-pantalla-85-300x231.png 300w, https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/Captura-de-pantalla-85-260x200.png 260w\" sizes=\"(max-width: 592px) 100vw, 592px\" \/><\/p>\n<p style=\"text-align: justify;\">El D\u00eda Internacional de la Mujer es una fecha para reflexionar sobre los avances logrados en materia de igualdad, reconocer el trabajo, valent\u00eda y determinaci\u00f3n que las mujeres cumplen en la historia de sus comunidades y el mundo entero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las mujeres de Nari\u00f1o son aquellas que d\u00eda a d\u00eda se levantan a conquistar sus sue\u00f1os y liderar espacios de toma de decisiones que potencian el desarrollo de un territorio competitivo, sostenible, conectado, seguro, incluyente y en paz. Desde la Gobernaci\u00f3n de Nari\u00f1o conmemoramos esta fecha que permite recordarle a la sociedad, la lucha por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":51037,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[],"class_list":["post-51035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regiones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nari\u00f1o conmemora y resalta la lucha de las mujeres por un futuro incluyente y en paz. | P\u00e1gina10<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nari\u00f1o conmemora y resalta la lucha de las mujeres por un futuro incluyente y en paz. | P\u00e1gina10\" \/>\n<meta property=\"og:description\" content=\"Las mujeres de Nari\u00f1o son aquellas que d\u00eda a d\u00eda se levantan a conquistar sus sue\u00f1os y liderar espacios de toma de decisiones que potencian el desarrollo de un territorio competitivo, sostenible, conectado, seguro, incluyente y en paz. Desde la Gobernaci\u00f3n de Nari\u00f1o conmemoramos esta fecha que permite recordarle a la sociedad, la lucha por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/\" \/>\n<meta property=\"og:site_name\" content=\"P\u00e1gina10\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pag10com\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-08T14:30:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/AFICHE-OFICIAL.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1144\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"P\u00e1gina 10\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Pag10com\" \/>\n<meta name=\"twitter:site\" content=\"@Pag10com\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"P\u00e1gina 10\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/\"},\"author\":{\"name\":\"P\u00e1gina 10\",\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/person\/2efc4a090d25b667d3bc796798a3a81b\"},\"headline\":\"Nari\u00f1o conmemora y resalta la lucha de las mujeres por un futuro incluyente y en paz.\",\"datePublished\":\"2021-03-08T14:30:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/\"},\"wordCount\":286,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/pagina10.com\/web\/#organization\"},\"image\":{\"@id\":\"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/AFICHE-OFICIAL.jpeg\",\"articleSection\":[\"Regiones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/\",\"url\":\"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/\",\"name\":\"Nari\u00f1o conmemora y resalta la lucha de las mujeres por un futuro incluyente y en paz. | P\u00e1gina10\",\"isPartOf\":{\"@id\":\"https:\/\/pagina10.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/AFICHE-OFICIAL.jpeg\",\"datePublished\":\"2021-03-08T14:30:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/#primaryimage\",\"url\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/AFICHE-OFICIAL.jpeg\",\"contentUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/AFICHE-OFICIAL.jpeg\",\"width\":1144,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/pagina10.com\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nari\u00f1o conmemora y resalta la lucha de las mujeres por un futuro incluyente y en paz.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pagina10.com\/web\/#website\",\"url\":\"https:\/\/pagina10.com\/web\/\",\"name\":\"P\u00e1gina10\",\"description\":\"Peri\u00f3dico Regional\",\"publisher\":{\"@id\":\"https:\/\/pagina10.com\/web\/#organization\"},\"alternateName\":\"P\u00e1gina10 Peri\u00f3dico Regional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pagina10.com\/web\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pagina10.com\/web\/#organization\",\"name\":\"P\u00e1gina10\",\"alternateName\":\"P\u00e1gina10 Peri\u00f3dico Regional\",\"url\":\"https:\/\/pagina10.com\/web\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg\",\"contentUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg\",\"width\":1280,\"height\":720,\"caption\":\"P\u00e1gina10\"},\"image\":{\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pag10com\",\"https:\/\/x.com\/Pag10com\",\"https:\/\/www.instagram.com\/pagina10col\/\",\"https:\/\/youtube.com\/channel\/pag10\",\"https:\/\/www.tiktok.com\/@p10col\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/person\/2efc4a090d25b667d3bc796798a3a81b\",\"name\":\"P\u00e1gina 10\",\"description\":\"P\u00e1gina 10 es un peri\u00f3dico regional que nace en Colombia, en el departamento de Nari\u00f1o, con un enfoque global, fundamentado en cuatro pilares esenciales: la libertad, el pluralismo, la inclusi\u00f3n y la independencia. P\u00e1gina 10 hace referencia a Nari\u00f1o como el d\u00e9cimo departamento creado en Colombia, despu\u00e9s de un proceso pol\u00edtico liderado por actores y actrices regionales con el fin de obtener la independencia y autonom\u00eda de nuestros territorios. Con la creaci\u00f3n de P\u00e1gina 10 se pretende abrir un escenario para el dialogo, la reflexi\u00f3n y el debate que se extienda a otras geograf\u00edas de Am\u00e9rica Latina y del planeta, en una apuesta por transformar colectivamente los desaf\u00edos de un mundo contempor\u00e1neo, m\u00e1s all\u00e1 de las fronteras impuestas.\",\"url\":\"https:\/\/pagina10.com\/web\/author\/pdiezadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nari\u00f1o conmemora y resalta la lucha de las mujeres por un futuro incluyente y en paz. | P\u00e1gina10","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/","og_locale":"es_ES","og_type":"article","og_title":"Nari\u00f1o conmemora y resalta la lucha de las mujeres por un futuro incluyente y en paz. | P\u00e1gina10","og_description":"Las mujeres de Nari\u00f1o son aquellas que d\u00eda a d\u00eda se levantan a conquistar sus sue\u00f1os y liderar espacios de toma de decisiones que potencian el desarrollo de un territorio competitivo, sostenible, conectado, seguro, incluyente y en paz. Desde la Gobernaci\u00f3n de Nari\u00f1o conmemoramos esta fecha que permite recordarle a la sociedad, la lucha por [&hellip;]","og_url":"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/","og_site_name":"P\u00e1gina10","article_publisher":"https:\/\/www.facebook.com\/pag10com","article_published_time":"2021-03-08T14:30:42+00:00","og_image":[{"width":1144,"height":1280,"url":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/AFICHE-OFICIAL.jpeg","type":"image\/jpeg"}],"author":"P\u00e1gina 10","twitter_card":"summary_large_image","twitter_creator":"@Pag10com","twitter_site":"@Pag10com","twitter_misc":{"Escrito por":"P\u00e1gina 10","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/#article","isPartOf":{"@id":"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/"},"author":{"name":"P\u00e1gina 10","@id":"https:\/\/pagina10.com\/web\/#\/schema\/person\/2efc4a090d25b667d3bc796798a3a81b"},"headline":"Nari\u00f1o conmemora y resalta la lucha de las mujeres por un futuro incluyente y en paz.","datePublished":"2021-03-08T14:30:42+00:00","mainEntityOfPage":{"@id":"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/"},"wordCount":286,"commentCount":0,"publisher":{"@id":"https:\/\/pagina10.com\/web\/#organization"},"image":{"@id":"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/#primaryimage"},"thumbnailUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/AFICHE-OFICIAL.jpeg","articleSection":["Regiones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/","url":"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/","name":"Nari\u00f1o conmemora y resalta la lucha de las mujeres por un futuro incluyente y en paz. | P\u00e1gina10","isPartOf":{"@id":"https:\/\/pagina10.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/#primaryimage"},"image":{"@id":"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/#primaryimage"},"thumbnailUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/AFICHE-OFICIAL.jpeg","datePublished":"2021-03-08T14:30:42+00:00","breadcrumb":{"@id":"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/#primaryimage","url":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/AFICHE-OFICIAL.jpeg","contentUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/AFICHE-OFICIAL.jpeg","width":1144,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/pagina10.com\/web\/narino-conmemora-y-resalta-la-lucha-de-las-mujeres-por-un-futuro-incluyente-y-en-paz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pagina10.com\/web\/"},{"@type":"ListItem","position":2,"name":"Nari\u00f1o conmemora y resalta la lucha de las mujeres por un futuro incluyente y en paz."}]},{"@type":"WebSite","@id":"https:\/\/pagina10.com\/web\/#website","url":"https:\/\/pagina10.com\/web\/","name":"P\u00e1gina10","description":"Peri\u00f3dico Regional","publisher":{"@id":"https:\/\/pagina10.com\/web\/#organization"},"alternateName":"P\u00e1gina10 Peri\u00f3dico Regional","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pagina10.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pagina10.com\/web\/#organization","name":"P\u00e1gina10","alternateName":"P\u00e1gina10 Peri\u00f3dico Regional","url":"https:\/\/pagina10.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/","url":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg","contentUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg","width":1280,"height":720,"caption":"P\u00e1gina10"},"image":{"@id":"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pag10com","https:\/\/x.com\/Pag10com","https:\/\/www.instagram.com\/pagina10col\/","https:\/\/youtube.com\/channel\/pag10","https:\/\/www.tiktok.com\/@p10col"]},{"@type":"Person","@id":"https:\/\/pagina10.com\/web\/#\/schema\/person\/2efc4a090d25b667d3bc796798a3a81b","name":"P\u00e1gina 10","description":"P\u00e1gina 10 es un peri\u00f3dico regional que nace en Colombia, en el departamento de Nari\u00f1o, con un enfoque global, fundamentado en cuatro pilares esenciales: la libertad, el pluralismo, la inclusi\u00f3n y la independencia. P\u00e1gina 10 hace referencia a Nari\u00f1o como el d\u00e9cimo departamento creado en Colombia, despu\u00e9s de un proceso pol\u00edtico liderado por actores y actrices regionales con el fin de obtener la independencia y autonom\u00eda de nuestros territorios. Con la creaci\u00f3n de P\u00e1gina 10 se pretende abrir un escenario para el dialogo, la reflexi\u00f3n y el debate que se extienda a otras geograf\u00edas de Am\u00e9rica Latina y del planeta, en una apuesta por transformar colectivamente los desaf\u00edos de un mundo contempor\u00e1neo, m\u00e1s all\u00e1 de las fronteras impuestas.","url":"https:\/\/pagina10.com\/web\/author\/pdiezadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts\/51035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/comments?post=51035"}],"version-history":[{"count":1,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts\/51035\/revisions"}],"predecessor-version":[{"id":51038,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts\/51035\/revisions\/51038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/media\/51037"}],"wp:attachment":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/media?parent=51035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/categories?post=51035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/tags?post=51035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}