{"id":51211,"date":"2021-03-17T12:58:17","date_gmt":"2021-03-17T17:58:17","guid":{"rendered":"https:\/\/pagina10.com\/web\/?p=51211"},"modified":"2021-03-17T12:58:17","modified_gmt":"2021-03-17T17:58:17","slug":"gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas","status":"publish","type":"post","link":"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/","title":{"rendered":"Gobernaci\u00f3n entreg\u00f3 ambulancia y dotaci\u00f3n de bioseguridad en apertura de nuevo hospital de Barbacoas."},"content":{"rendered":"<p style=\"text-align: justify;\">Con el objetivo de fortalecer la red hospitalaria del Departamento, la Gobernaci\u00f3n de Nari\u00f1o entreg\u00f3 al Hospital San Antonio, del Municipio de Barbacoas, una ambulancia y elementos de bioseguridad. La dotaci\u00f3n de estos elementos se realiz\u00f3 en la apertura de este Hospital.<\/p>\n<p>El Gobernador de Nari\u00f1o, explic\u00f3 que el funcionamiento del Hospital San Antonio es posible gracias a la Gesti\u00f3n realizada por el Gobierno Departamental que permiti\u00f3 obtener recursos por los $2.390 millones para el pago al personal de la salud en el Municipio de Barbacoas.<\/p>\n<p>\u201cHoy entregamos dotaci\u00f3n de elementos de bioseguridad por $310 millones, para la protecci\u00f3n del personal m\u00e9dico asistencial. Y lo m\u00e1s importante, hicimos la gesti\u00f3n para que el Hospital salga del problema fiscal y financiero para el pago de los trabajadores\u201d, se\u00f1al\u00f3 el Gobernador de Nari\u00f1o, Jhon Rojas.<\/p>\n<p>Todas estas entregas se realizan a trav\u00e9s de una estrategia articulada entre el Gobierno Nacional, Departamental y Municipal. \u201cAgradecemos de manera especial no solo su presencia Gobernador, si no, el cari\u00f1o que le ha demostrado a nuestro Municipio con creces, con los recursos que le ha tra\u00eddo a nuestra regi\u00f3n\u201d, indic\u00f3 el Alcalde de Barbacoas,<\/p>\n<p>Avance de obras v\u00eda Jun\u00edn -Barbacoas<\/p>\n<p>El Gobernador de Nari\u00f1o, Jhon Rojas, visit\u00f3 los frentes de trabajo de la v\u00eda Jun\u00edn &#8211; Barbacoas, para constatar el avance en la pavimentaci\u00f3n de esta v\u00eda en los tramos a cargo del Batall\u00f3n de Ingenieros del Ej\u00e9rcito Nacional y de la firma Sonacol. El mandatario seccional se mostr\u00f3 satisfecho con el trabajo cumplido y reiter\u00f3 que la pavimentaci\u00f3n de esta v\u00eda es una realidad y que pronto Inv\u00edas entregar\u00e1 los estudios del tramo de la Culumpia.<\/p>\n<p>El Gobernador indic\u00f3 que tambi\u00e9n se adelantan los estudios y dise\u00f1os para el Puente sobre el R\u00edo Telemb\u00ed y el corredor vial hacia Mag\u00fc\u00ed Pay\u00e1n, obra prioritaria para interconectar a los habitantes del denominado tri\u00e1ngulo del Telemb\u00cd.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el objetivo de fortalecer la red hospitalaria del Departamento, la Gobernaci\u00f3n de Nari\u00f1o entreg\u00f3 al Hospital San Antonio, del Municipio de Barbacoas, una ambulancia y elementos de bioseguridad. La dotaci\u00f3n de estos elementos se realiz\u00f3 en la apertura de este Hospital. El Gobernador de Nari\u00f1o, explic\u00f3 que el funcionamiento del Hospital San Antonio es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":51212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[],"class_list":["post-51211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regiones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gobernaci\u00f3n entreg\u00f3 ambulancia y dotaci\u00f3n de bioseguridad en apertura de nuevo hospital de Barbacoas. | P\u00e1gina10<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobernaci\u00f3n entreg\u00f3 ambulancia y dotaci\u00f3n de bioseguridad en apertura de nuevo hospital de Barbacoas. | P\u00e1gina10\" \/>\n<meta property=\"og:description\" content=\"Con el objetivo de fortalecer la red hospitalaria del Departamento, la Gobernaci\u00f3n de Nari\u00f1o entreg\u00f3 al Hospital San Antonio, del Municipio de Barbacoas, una ambulancia y elementos de bioseguridad. La dotaci\u00f3n de estos elementos se realiz\u00f3 en la apertura de este Hospital. El Gobernador de Nari\u00f1o, explic\u00f3 que el funcionamiento del Hospital San Antonio es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/\" \/>\n<meta property=\"og:site_name\" content=\"P\u00e1gina10\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pag10com\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-17T17:58:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/Captura-de-pantalla-108.png\" \/>\n\t<meta property=\"og:image:width\" content=\"510\" \/>\n\t<meta property=\"og:image:height\" content=\"336\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"P\u00e1gina 10\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Pag10com\" \/>\n<meta name=\"twitter:site\" content=\"@Pag10com\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"P\u00e1gina 10\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/\"},\"author\":{\"name\":\"P\u00e1gina 10\",\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/person\/2efc4a090d25b667d3bc796798a3a81b\"},\"headline\":\"Gobernaci\u00f3n entreg\u00f3 ambulancia y dotaci\u00f3n de bioseguridad en apertura de nuevo hospital de Barbacoas.\",\"datePublished\":\"2021-03-17T17:58:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/\"},\"wordCount\":355,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/pagina10.com\/web\/#organization\"},\"image\":{\"@id\":\"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/Captura-de-pantalla-108.png\",\"articleSection\":[\"Regiones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/\",\"url\":\"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/\",\"name\":\"Gobernaci\u00f3n entreg\u00f3 ambulancia y dotaci\u00f3n de bioseguridad en apertura de nuevo hospital de Barbacoas. | P\u00e1gina10\",\"isPartOf\":{\"@id\":\"https:\/\/pagina10.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/Captura-de-pantalla-108.png\",\"datePublished\":\"2021-03-17T17:58:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/#primaryimage\",\"url\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/Captura-de-pantalla-108.png\",\"contentUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/Captura-de-pantalla-108.png\",\"width\":510,\"height\":336},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/pagina10.com\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobernaci\u00f3n entreg\u00f3 ambulancia y dotaci\u00f3n de bioseguridad en apertura de nuevo hospital de Barbacoas.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pagina10.com\/web\/#website\",\"url\":\"https:\/\/pagina10.com\/web\/\",\"name\":\"P\u00e1gina10\",\"description\":\"Peri\u00f3dico Regional\",\"publisher\":{\"@id\":\"https:\/\/pagina10.com\/web\/#organization\"},\"alternateName\":\"P\u00e1gina10 Peri\u00f3dico Regional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pagina10.com\/web\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pagina10.com\/web\/#organization\",\"name\":\"P\u00e1gina10\",\"alternateName\":\"P\u00e1gina10 Peri\u00f3dico Regional\",\"url\":\"https:\/\/pagina10.com\/web\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg\",\"contentUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg\",\"width\":1280,\"height\":720,\"caption\":\"P\u00e1gina10\"},\"image\":{\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pag10com\",\"https:\/\/x.com\/Pag10com\",\"https:\/\/www.instagram.com\/pagina10col\/\",\"https:\/\/youtube.com\/channel\/pag10\",\"https:\/\/www.tiktok.com\/@p10col\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/person\/2efc4a090d25b667d3bc796798a3a81b\",\"name\":\"P\u00e1gina 10\",\"description\":\"P\u00e1gina 10 es un peri\u00f3dico regional que nace en Colombia, en el departamento de Nari\u00f1o, con un enfoque global, fundamentado en cuatro pilares esenciales: la libertad, el pluralismo, la inclusi\u00f3n y la independencia. P\u00e1gina 10 hace referencia a Nari\u00f1o como el d\u00e9cimo departamento creado en Colombia, despu\u00e9s de un proceso pol\u00edtico liderado por actores y actrices regionales con el fin de obtener la independencia y autonom\u00eda de nuestros territorios. Con la creaci\u00f3n de P\u00e1gina 10 se pretende abrir un escenario para el dialogo, la reflexi\u00f3n y el debate que se extienda a otras geograf\u00edas de Am\u00e9rica Latina y del planeta, en una apuesta por transformar colectivamente los desaf\u00edos de un mundo contempor\u00e1neo, m\u00e1s all\u00e1 de las fronteras impuestas.\",\"url\":\"https:\/\/pagina10.com\/web\/author\/pdiezadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobernaci\u00f3n entreg\u00f3 ambulancia y dotaci\u00f3n de bioseguridad en apertura de nuevo hospital de Barbacoas. | P\u00e1gina10","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/","og_locale":"es_ES","og_type":"article","og_title":"Gobernaci\u00f3n entreg\u00f3 ambulancia y dotaci\u00f3n de bioseguridad en apertura de nuevo hospital de Barbacoas. | P\u00e1gina10","og_description":"Con el objetivo de fortalecer la red hospitalaria del Departamento, la Gobernaci\u00f3n de Nari\u00f1o entreg\u00f3 al Hospital San Antonio, del Municipio de Barbacoas, una ambulancia y elementos de bioseguridad. La dotaci\u00f3n de estos elementos se realiz\u00f3 en la apertura de este Hospital. El Gobernador de Nari\u00f1o, explic\u00f3 que el funcionamiento del Hospital San Antonio es [&hellip;]","og_url":"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/","og_site_name":"P\u00e1gina10","article_publisher":"https:\/\/www.facebook.com\/pag10com","article_published_time":"2021-03-17T17:58:17+00:00","og_image":[{"width":510,"height":336,"url":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/Captura-de-pantalla-108.png","type":"image\/png"}],"author":"P\u00e1gina 10","twitter_card":"summary_large_image","twitter_creator":"@Pag10com","twitter_site":"@Pag10com","twitter_misc":{"Escrito por":"P\u00e1gina 10","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/#article","isPartOf":{"@id":"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/"},"author":{"name":"P\u00e1gina 10","@id":"https:\/\/pagina10.com\/web\/#\/schema\/person\/2efc4a090d25b667d3bc796798a3a81b"},"headline":"Gobernaci\u00f3n entreg\u00f3 ambulancia y dotaci\u00f3n de bioseguridad en apertura de nuevo hospital de Barbacoas.","datePublished":"2021-03-17T17:58:17+00:00","mainEntityOfPage":{"@id":"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/"},"wordCount":355,"commentCount":0,"publisher":{"@id":"https:\/\/pagina10.com\/web\/#organization"},"image":{"@id":"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/#primaryimage"},"thumbnailUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/Captura-de-pantalla-108.png","articleSection":["Regiones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/","url":"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/","name":"Gobernaci\u00f3n entreg\u00f3 ambulancia y dotaci\u00f3n de bioseguridad en apertura de nuevo hospital de Barbacoas. | P\u00e1gina10","isPartOf":{"@id":"https:\/\/pagina10.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/#primaryimage"},"image":{"@id":"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/#primaryimage"},"thumbnailUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/Captura-de-pantalla-108.png","datePublished":"2021-03-17T17:58:17+00:00","breadcrumb":{"@id":"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/#primaryimage","url":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/Captura-de-pantalla-108.png","contentUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/03\/Captura-de-pantalla-108.png","width":510,"height":336},{"@type":"BreadcrumbList","@id":"https:\/\/pagina10.com\/web\/gobernacion-entrego-ambulancia-y-dotacion-de-bioseguridad-en-apertura-de-nuevo-hospital-de-barbacoas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pagina10.com\/web\/"},{"@type":"ListItem","position":2,"name":"Gobernaci\u00f3n entreg\u00f3 ambulancia y dotaci\u00f3n de bioseguridad en apertura de nuevo hospital de Barbacoas."}]},{"@type":"WebSite","@id":"https:\/\/pagina10.com\/web\/#website","url":"https:\/\/pagina10.com\/web\/","name":"P\u00e1gina10","description":"Peri\u00f3dico Regional","publisher":{"@id":"https:\/\/pagina10.com\/web\/#organization"},"alternateName":"P\u00e1gina10 Peri\u00f3dico Regional","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pagina10.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pagina10.com\/web\/#organization","name":"P\u00e1gina10","alternateName":"P\u00e1gina10 Peri\u00f3dico Regional","url":"https:\/\/pagina10.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/","url":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg","contentUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg","width":1280,"height":720,"caption":"P\u00e1gina10"},"image":{"@id":"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pag10com","https:\/\/x.com\/Pag10com","https:\/\/www.instagram.com\/pagina10col\/","https:\/\/youtube.com\/channel\/pag10","https:\/\/www.tiktok.com\/@p10col"]},{"@type":"Person","@id":"https:\/\/pagina10.com\/web\/#\/schema\/person\/2efc4a090d25b667d3bc796798a3a81b","name":"P\u00e1gina 10","description":"P\u00e1gina 10 es un peri\u00f3dico regional que nace en Colombia, en el departamento de Nari\u00f1o, con un enfoque global, fundamentado en cuatro pilares esenciales: la libertad, el pluralismo, la inclusi\u00f3n y la independencia. P\u00e1gina 10 hace referencia a Nari\u00f1o como el d\u00e9cimo departamento creado en Colombia, despu\u00e9s de un proceso pol\u00edtico liderado por actores y actrices regionales con el fin de obtener la independencia y autonom\u00eda de nuestros territorios. Con la creaci\u00f3n de P\u00e1gina 10 se pretende abrir un escenario para el dialogo, la reflexi\u00f3n y el debate que se extienda a otras geograf\u00edas de Am\u00e9rica Latina y del planeta, en una apuesta por transformar colectivamente los desaf\u00edos de un mundo contempor\u00e1neo, m\u00e1s all\u00e1 de las fronteras impuestas.","url":"https:\/\/pagina10.com\/web\/author\/pdiezadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts\/51211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/comments?post=51211"}],"version-history":[{"count":1,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts\/51211\/revisions"}],"predecessor-version":[{"id":51213,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts\/51211\/revisions\/51213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/media\/51212"}],"wp:attachment":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/media?parent=51211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/categories?post=51211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/tags?post=51211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}