{"id":51560,"date":"2021-04-05T10:50:04","date_gmt":"2021-04-05T15:50:04","guid":{"rendered":"https:\/\/pagina10.com\/web\/?p=51560"},"modified":"2021-04-06T09:59:45","modified_gmt":"2021-04-06T14:59:45","slug":"explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte","status":"publish","type":"post","link":"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/","title":{"rendered":"Explosi\u00f3n en transformador deja sin energ\u00eda a todo Nari\u00f1o, excepto la zona norte."},"content":{"rendered":"<p style=\"text-align: justify;\">Cedenar informa que desde las 9:30 am se presenta un da\u00f1o por explosi\u00f3n en transformador de corriente de la bah\u00eda de l\u00ednea 115 kV en Subestaci\u00f3n Jamondino, que deja sin servicio de energ\u00eda a todo el departamento de Nari\u00f1o, excepto la zona norte.<\/p>\n<p style=\"text-align: justify;\">Personal t\u00e9cnico de la empresa se encuentra realizando las maniobras correspondientes para normalizar el servicio de energ\u00eda en el menor tiempo posible.<\/p>\n<p style=\"text-align: justify;\">Se espera que antes del medio d\u00eda se resuelva el problema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cedenar informa que desde las 9:30 am se presenta un da\u00f1o por explosi\u00f3n en transformador de corriente de la bah\u00eda de l\u00ednea 115 kV en Subestaci\u00f3n Jamondino, que deja sin servicio de energ\u00eda a todo el departamento de Nari\u00f1o, excepto la zona norte. Personal t\u00e9cnico de la empresa se encuentra realizando las maniobras correspondientes para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":51561,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[],"class_list":["post-51560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regiones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Explosi\u00f3n en transformador deja sin energ\u00eda a todo Nari\u00f1o, excepto la zona norte. | P\u00e1gina10<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Explosi\u00f3n en transformador deja sin energ\u00eda a todo Nari\u00f1o, excepto la zona norte. | P\u00e1gina10\" \/>\n<meta property=\"og:description\" content=\"Cedenar informa que desde las 9:30 am se presenta un da\u00f1o por explosi\u00f3n en transformador de corriente de la bah\u00eda de l\u00ednea 115 kV en Subestaci\u00f3n Jamondino, que deja sin servicio de energ\u00eda a todo el departamento de Nari\u00f1o, excepto la zona norte. Personal t\u00e9cnico de la empresa se encuentra realizando las maniobras correspondientes para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/\" \/>\n<meta property=\"og:site_name\" content=\"P\u00e1gina10\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pag10com\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-05T15:50:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-06T14:59:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/04\/cedenar-blackwhite.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"P\u00e1gina 10\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Pag10com\" \/>\n<meta name=\"twitter:site\" content=\"@Pag10com\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"P\u00e1gina 10\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/\"},\"author\":{\"name\":\"P\u00e1gina 10\",\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/person\/2efc4a090d25b667d3bc796798a3a81b\"},\"headline\":\"Explosi\u00f3n en transformador deja sin energ\u00eda a todo Nari\u00f1o, excepto la zona norte.\",\"datePublished\":\"2021-04-05T15:50:04+00:00\",\"dateModified\":\"2021-04-06T14:59:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/\"},\"wordCount\":100,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/pagina10.com\/web\/#organization\"},\"image\":{\"@id\":\"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/04\/cedenar-blackwhite.jpg\",\"articleSection\":[\"Regiones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/\",\"url\":\"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/\",\"name\":\"Explosi\u00f3n en transformador deja sin energ\u00eda a todo Nari\u00f1o, excepto la zona norte. | P\u00e1gina10\",\"isPartOf\":{\"@id\":\"https:\/\/pagina10.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/04\/cedenar-blackwhite.jpg\",\"datePublished\":\"2021-04-05T15:50:04+00:00\",\"dateModified\":\"2021-04-06T14:59:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/#primaryimage\",\"url\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/04\/cedenar-blackwhite.jpg\",\"contentUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/04\/cedenar-blackwhite.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/pagina10.com\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Explosi\u00f3n en transformador deja sin energ\u00eda a todo Nari\u00f1o, excepto la zona norte.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pagina10.com\/web\/#website\",\"url\":\"https:\/\/pagina10.com\/web\/\",\"name\":\"P\u00e1gina10\",\"description\":\"Peri\u00f3dico Regional\",\"publisher\":{\"@id\":\"https:\/\/pagina10.com\/web\/#organization\"},\"alternateName\":\"P\u00e1gina10 Peri\u00f3dico Regional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pagina10.com\/web\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pagina10.com\/web\/#organization\",\"name\":\"P\u00e1gina10\",\"alternateName\":\"P\u00e1gina10 Peri\u00f3dico Regional\",\"url\":\"https:\/\/pagina10.com\/web\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg\",\"contentUrl\":\"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg\",\"width\":1280,\"height\":720,\"caption\":\"P\u00e1gina10\"},\"image\":{\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pag10com\",\"https:\/\/x.com\/Pag10com\",\"https:\/\/www.instagram.com\/pagina10col\/\",\"https:\/\/youtube.com\/channel\/pag10\",\"https:\/\/www.tiktok.com\/@p10col\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/pagina10.com\/web\/#\/schema\/person\/2efc4a090d25b667d3bc796798a3a81b\",\"name\":\"P\u00e1gina 10\",\"description\":\"P\u00e1gina 10 es un peri\u00f3dico regional que nace en Colombia, en el departamento de Nari\u00f1o, con un enfoque global, fundamentado en cuatro pilares esenciales: la libertad, el pluralismo, la inclusi\u00f3n y la independencia. P\u00e1gina 10 hace referencia a Nari\u00f1o como el d\u00e9cimo departamento creado en Colombia, despu\u00e9s de un proceso pol\u00edtico liderado por actores y actrices regionales con el fin de obtener la independencia y autonom\u00eda de nuestros territorios. Con la creaci\u00f3n de P\u00e1gina 10 se pretende abrir un escenario para el dialogo, la reflexi\u00f3n y el debate que se extienda a otras geograf\u00edas de Am\u00e9rica Latina y del planeta, en una apuesta por transformar colectivamente los desaf\u00edos de un mundo contempor\u00e1neo, m\u00e1s all\u00e1 de las fronteras impuestas.\",\"url\":\"https:\/\/pagina10.com\/web\/author\/pdiezadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Explosi\u00f3n en transformador deja sin energ\u00eda a todo Nari\u00f1o, excepto la zona norte. | P\u00e1gina10","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/","og_locale":"es_ES","og_type":"article","og_title":"Explosi\u00f3n en transformador deja sin energ\u00eda a todo Nari\u00f1o, excepto la zona norte. | P\u00e1gina10","og_description":"Cedenar informa que desde las 9:30 am se presenta un da\u00f1o por explosi\u00f3n en transformador de corriente de la bah\u00eda de l\u00ednea 115 kV en Subestaci\u00f3n Jamondino, que deja sin servicio de energ\u00eda a todo el departamento de Nari\u00f1o, excepto la zona norte. Personal t\u00e9cnico de la empresa se encuentra realizando las maniobras correspondientes para [&hellip;]","og_url":"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/","og_site_name":"P\u00e1gina10","article_publisher":"https:\/\/www.facebook.com\/pag10com","article_published_time":"2021-04-05T15:50:04+00:00","article_modified_time":"2021-04-06T14:59:45+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/04\/cedenar-blackwhite.jpg","type":"image\/jpeg"}],"author":"P\u00e1gina 10","twitter_card":"summary_large_image","twitter_creator":"@Pag10com","twitter_site":"@Pag10com","twitter_misc":{"Escrito por":"P\u00e1gina 10"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/#article","isPartOf":{"@id":"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/"},"author":{"name":"P\u00e1gina 10","@id":"https:\/\/pagina10.com\/web\/#\/schema\/person\/2efc4a090d25b667d3bc796798a3a81b"},"headline":"Explosi\u00f3n en transformador deja sin energ\u00eda a todo Nari\u00f1o, excepto la zona norte.","datePublished":"2021-04-05T15:50:04+00:00","dateModified":"2021-04-06T14:59:45+00:00","mainEntityOfPage":{"@id":"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/"},"wordCount":100,"commentCount":0,"publisher":{"@id":"https:\/\/pagina10.com\/web\/#organization"},"image":{"@id":"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/#primaryimage"},"thumbnailUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/04\/cedenar-blackwhite.jpg","articleSection":["Regiones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/","url":"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/","name":"Explosi\u00f3n en transformador deja sin energ\u00eda a todo Nari\u00f1o, excepto la zona norte. | P\u00e1gina10","isPartOf":{"@id":"https:\/\/pagina10.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/#primaryimage"},"image":{"@id":"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/#primaryimage"},"thumbnailUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/04\/cedenar-blackwhite.jpg","datePublished":"2021-04-05T15:50:04+00:00","dateModified":"2021-04-06T14:59:45+00:00","breadcrumb":{"@id":"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/#primaryimage","url":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/04\/cedenar-blackwhite.jpg","contentUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2021\/04\/cedenar-blackwhite.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/pagina10.com\/web\/explosion-en-transformador-deja-sin-energia-a-todo-narino-excepto-la-zona-norte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pagina10.com\/web\/"},{"@type":"ListItem","position":2,"name":"Explosi\u00f3n en transformador deja sin energ\u00eda a todo Nari\u00f1o, excepto la zona norte."}]},{"@type":"WebSite","@id":"https:\/\/pagina10.com\/web\/#website","url":"https:\/\/pagina10.com\/web\/","name":"P\u00e1gina10","description":"Peri\u00f3dico Regional","publisher":{"@id":"https:\/\/pagina10.com\/web\/#organization"},"alternateName":"P\u00e1gina10 Peri\u00f3dico Regional","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pagina10.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pagina10.com\/web\/#organization","name":"P\u00e1gina10","alternateName":"P\u00e1gina10 Peri\u00f3dico Regional","url":"https:\/\/pagina10.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/","url":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg","contentUrl":"https:\/\/pagina10.com\/web\/wp-content\/uploads\/2024\/01\/40-pagina-10-periodico-regional-pasto.jpg","width":1280,"height":720,"caption":"P\u00e1gina10"},"image":{"@id":"https:\/\/pagina10.com\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pag10com","https:\/\/x.com\/Pag10com","https:\/\/www.instagram.com\/pagina10col\/","https:\/\/youtube.com\/channel\/pag10","https:\/\/www.tiktok.com\/@p10col"]},{"@type":"Person","@id":"https:\/\/pagina10.com\/web\/#\/schema\/person\/2efc4a090d25b667d3bc796798a3a81b","name":"P\u00e1gina 10","description":"P\u00e1gina 10 es un peri\u00f3dico regional que nace en Colombia, en el departamento de Nari\u00f1o, con un enfoque global, fundamentado en cuatro pilares esenciales: la libertad, el pluralismo, la inclusi\u00f3n y la independencia. P\u00e1gina 10 hace referencia a Nari\u00f1o como el d\u00e9cimo departamento creado en Colombia, despu\u00e9s de un proceso pol\u00edtico liderado por actores y actrices regionales con el fin de obtener la independencia y autonom\u00eda de nuestros territorios. Con la creaci\u00f3n de P\u00e1gina 10 se pretende abrir un escenario para el dialogo, la reflexi\u00f3n y el debate que se extienda a otras geograf\u00edas de Am\u00e9rica Latina y del planeta, en una apuesta por transformar colectivamente los desaf\u00edos de un mundo contempor\u00e1neo, m\u00e1s all\u00e1 de las fronteras impuestas.","url":"https:\/\/pagina10.com\/web\/author\/pdiezadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts\/51560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/comments?post=51560"}],"version-history":[{"count":4,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts\/51560\/revisions"}],"predecessor-version":[{"id":51588,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/posts\/51560\/revisions\/51588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/media\/51561"}],"wp:attachment":[{"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/media?parent=51560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/categories?post=51560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pagina10.com\/web\/wp-json\/wp\/v2\/tags?post=51560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}